{"id":273,"count":22,"description":"","link":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/","name":"Healthcare Facilities","slug":"ref-hospitals","taxonomy":"portfolio_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Healthcare Facilities archivos - LDA Audio Tech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Healthcare Facilities archivos - LDA Audio Tech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/\" \/>\n<meta property=\"og:site_name\" content=\"LDA Audio Tech\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LDAAudioTech\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/portfolio-category\\\/ref-hospitals\\\/\",\"url\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/portfolio-category\\\/ref-hospitals\\\/\",\"name\":\"Healthcare Facilities archivos - LDA Audio Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/portfolio-category\\\/ref-hospitals\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/portfolio-category\\\/ref-hospitals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Healthcare Facilities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/\",\"name\":\"LDA Audio Tech\",\"description\":\"Integrated Audio Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#organization\"},\"alternateName\":\"LDA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#organization\",\"name\":\"LDA Audio Tech\",\"alternateName\":\"LDA\",\"url\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lda-audiotech.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/logo-lda-color.png\",\"contentUrl\":\"https:\\\/\\\/lda-audiotech.com\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/logo-lda-color.png\",\"width\":169,\"height\":90,\"caption\":\"LDA Audio Tech\"},\"image\":{\"@id\":\"https:\\\/\\\/lda-audiotech.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LDAaudiotech\\\/\",\"https:\\\/\\\/x.com\\\/LDAAudioTech\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lda-audio-tech\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/LDAaudiotech\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Healthcare Facilities archivos - LDA Audio Tech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/","og_locale":"en_US","og_type":"article","og_title":"Healthcare Facilities archivos - LDA Audio Tech","og_url":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/","og_site_name":"LDA Audio Tech","twitter_card":"summary_large_image","twitter_site":"@LDAAudioTech","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/","url":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/","name":"Healthcare Facilities archivos - LDA Audio Tech","isPartOf":{"@id":"https:\/\/lda-audiotech.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lda-audiotech.com\/en\/portfolio-category\/ref-hospitals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lda-audiotech.com\/en\/"},{"@type":"ListItem","position":2,"name":"Healthcare Facilities"}]},{"@type":"WebSite","@id":"https:\/\/lda-audiotech.com\/en\/#website","url":"https:\/\/lda-audiotech.com\/en\/","name":"LDA Audio Tech","description":"Integrated Audio Solutions","publisher":{"@id":"https:\/\/lda-audiotech.com\/en\/#organization"},"alternateName":"LDA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lda-audiotech.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lda-audiotech.com\/en\/#organization","name":"LDA Audio Tech","alternateName":"LDA","url":"https:\/\/lda-audiotech.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lda-audiotech.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lda-audiotech.com\/wp-content\/uploads\/2017\/05\/logo-lda-color.png","contentUrl":"https:\/\/lda-audiotech.com\/wp-content\/uploads\/2017\/05\/logo-lda-color.png","width":169,"height":90,"caption":"LDA Audio Tech"},"image":{"@id":"https:\/\/lda-audiotech.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LDAaudiotech\/","https:\/\/x.com\/LDAAudioTech","https:\/\/www.linkedin.com\/company\/lda-audio-tech","https:\/\/www.youtube.com\/user\/LDAaudiotech"]}]}},"_links":{"self":[{"href":"https:\/\/lda-audiotech.com\/en\/wp-json\/wp\/v2\/portfolio_category\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lda-audiotech.com\/en\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/lda-audiotech.com\/en\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"wp:post_type":[{"href":"https:\/\/lda-audiotech.com\/en\/wp-json\/wp\/v2\/portfolio_page?portfolio_category=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}